{"id":4674,"date":"2019-05-09T11:36:00","date_gmt":"2019-05-09T09:36:00","guid":{"rendered":"https:\/\/www.inometa.de\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/"},"modified":"2023-06-14T08:35:18","modified_gmt":"2023-06-14T06:35:18","slug":"inometa-bei-uns-steht-der-systemgedanke-im-vordergrund","status":"publish","type":"post","link":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/","title":{"rendered":"INOMETA \u2013 Bei uns steht der Systemgedanke im Vordergrund"},"content":{"rendered":"\r\n<p>Die Rasterwalze nimmt in der Flexodruckmaschine im Farb\u00fcbertragungsprozess eine herausragende Stellung ein.<\/p>\r\n\r\n\r\n\r\n<p>Allerdings muss f\u00fcr ein zufriedenstellendes Druckergebnis die rotierenden Komponenten in Druckwerk, Trocknung, Bahnf\u00fchrung und beim Wickeln exakt aufeinander abgestimmt sein. Welche Voraussetzungen gegeben sein m\u00fcssen und worauf dabei zu achten ist, dar\u00fcber sprach Flexo+Tief-Druck mit Stephan Palenga, Leiter Vertrieb Papier &amp; Print bei Inometa.<\/p>\r\n\r\n\r\n\r\n<p><strong>Zu den Kernkompetenzen von Inometa geh\u00f6rt die Entwicklung und Herstellung als auch die Beschichtung leichtgewichtiger Aluminium- und CFK-Walzen mit funktionalen Oberfl\u00e4chen f\u00fcr das Bedrucken, Veredeln und Beschichten von Papieren, Folien und anderen Substraten. Was sind die speziellen Herausforderungen im Bereich der Beschichtung von Aluminium-Rohren und CFK-H\u00fclsen?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong><em>\u00a0Die Herausforderungen sind stets unterschiedlich und abh\u00e4ngig von der jeweiligen Anwendung dieser Produkte. Bei jedem Beschichtungsvorgang besteht grunds\u00e4tzlich die besondere Aufgabenstellung darin, eine dauerhafte und gute Haftung der jeweiligen Auftragsmaterialien zu erreichen. Wichtig ist, die Temperaturbelastung im Beschichtungsprozess der Sleeves oder Walzen m\u00f6glichst gering zu halten. Nach meiner Einsch\u00e4tzung nimmt Inometa in diesem Bereich eine technologisch f\u00fchrende Position ein.<\/em><\/p>\r\n\r\n\r\n\r\n<p><strong>Beschreiben Sie bitte einige beispielhafte praktische Anwendungen dieser Produkte?\u00a0<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>In schnelllaufenden Flexodruckmaschinen mit gro\u00dfen Arbeitsbreiten, wie sie beispielsweise im Pre-Print oder Post-Print zum Einsatz kommen, werden aufgrund der Anforderungen an mechanische Stabilit\u00e4t oder Gewicht \u2013 Stichwort \u201eMassentr\u00e4gheit\u201c \u2013 Walzen aus CFK-Materialien eingesetzt.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Beim Einsatz von wasserbasierten Farben im Flexodruck oder beim Primern im Digitaldruck sind die Oberfl\u00e4chen von Rasterwalzen und Rasterwalzensleeves erh\u00f6hter Korrosion ausgesetzt und m\u00fcssen dieser Belastung daher standhalten. In diesem Zusammenhang bietet unsere GFK-Variante einen zuverl\u00e4ssigen und vollst\u00e4ndigen Schutz.<\/em><\/p>\r\n\r\n\r\n\r\n<p><strong>Inometa produziert rotierende Komponenten f\u00fcr nahezu alle Bereiche in Flexodruckmaschinen \u2013 sei es im Druckwerk, im Trockner, in der Bahnf\u00fchrung oder beim Wickeln. Welche Vorteile bietet dies f\u00fcr Inometa, OEMs und Druckereien?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>F\u00fcr unsere Kunden bietet das zuerst einmal den Vorteil eines einzigen Ansprechpartners f\u00fcr all diese Komponenten. Das gilt gleicherma\u00dfen f\u00fcr unsere Vertriebsmannschaft vor Ort wie f\u00fcr das Team im Sales Support, dem Service, dem Produktmanagement und der Entwicklung. All diese Bereiche zeichnen sich aus durch ein profundes Verst\u00e4ndnis f\u00fcr die Bed\u00fcrfnisse und Anforderungen unserer Kunden und deren jeweilige Branche.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>All unsere Produkte bieten technologisch f\u00fchrende, anwendungsorientierte und aufeinander abgestimmte L\u00f6sungen. Dabei steht der Systemgedanke klar im Vordergrund, wof\u00fcr ich unsere INOflex-Produktfamilie als besonderes Beispiel nennen m\u00f6chte.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Durch unser gutes Netzwerk und die vielen nationalen und internationalen Kundenkontakte sind wir oft der erste Ansprechpartner in den Druckereien und bei den OEMs. Es herrscht ein enger fachlicher Austausch bez\u00fcglich aller rotierender Komponenten im Flexodruck. Dabei wird uns eine Verantwortung \u00fcbertragen, die wir gerne \u00fcbernehmen.<\/em><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" class=\"wp-image-1111\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor.jpg\" alt=\"Inometa Stephan Palenga stellt vor\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor.jpg 1200w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-300x200.jpg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-1024x683.jpg 1024w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-768x512.jpg 768w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-800x533.jpg 800w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-1076x717.jpg 1076w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-525x350.jpg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-255x170.jpg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-stellt-vor-251x167.jpg 251w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\r\n\r\n\r\n\r\n<p><strong>Wie lassen sich diese Synergien praktisch nutzen?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:\u00a0<\/strong><em>Wir bieten unseren Kunden nachhaltige Produkte sowie einen schnellen und zielgerichteten Service. Die enge Vernetzung ist f\u00fcr uns eine wesentliche Unterst\u00fctzung in der Entwicklung neuer Produkte als Beitrag zur L\u00f6sung der produktionstechnischen Probleme unserer Kunden.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Die Leichtbauweise erlaubt eine sp\u00fcrbare Verkleinerung des Designs unserer Systeme, was zu Einsparungen im Materialeinsatz wie auch im Platzbedarf am sp\u00e4teren Einsatzort f\u00fchrt. Dar\u00fcber hinaus l\u00e4sst sich dadurch die Antriebsleistung der Maschinen niedriger und damit energiesparender auslegen. Dies erh\u00f6ht auch die Attraktivit\u00e4t der jeweiligen Arbeitspl\u00e4tze, denn das reduzierte Gewicht vereinfacht das Handling und verringert die damit verbundene k\u00f6rperliche Belastung.<\/em><\/p>\r\n\r\n\r\n\r\n<p><strong>\u00a0\u201eDie Rasterwalze bzw. der Rastersleeve ist die Seele des Flexodrucks\u201c ist nicht nur ein weit verbreitetes Zitat, sondern unterstreicht auch deren herausragende Bedeutung bei der Farb\u00fcbertragung im Flexodruck. Wie beurteilen Sie die Bedeutung der Rasterwalze im Gesamtprozess \u201eFlexodruck\u201c?<\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>Die Rasterwalze hat zweifellos einen signifikanten Einfluss auf den Druckprozess. Denn hochwertige Druckergebnisse lassen sich nur erzielen, wenn die Lineatur zum Klischee passt.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Ein weiterer wichtiger Aspekt ist die richtige und regelm\u00e4\u00dfige Reinigung der Rasterwalze zur Optimierung von Lebensdauer und Qualit\u00e4t der Walzenoberfl\u00e4che. Denn bei zu nachl\u00e4ssiger oder falscher Reinigung setzt sich die Zellstruktur immer zu. Dies f\u00fchrt zwangsl\u00e4ufig zu eingeschr\u00e4nkter Farb\u00fcbertrag und somit zu einem unzureichenden Druckergebnis. Daher ist die kontinuierliche Oberfl\u00e4chenreinigung bei Unterbrechungen wie auch beim Abschluss der jeweiligen Druckjobs von gro\u00dfer Bedeutung.<\/em><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" class=\"wp-image-1113\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1.jpg\" alt=\"Inometa Pr\u00fcfung\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1.jpg 1200w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-300x200.jpg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-1024x683.jpg 1024w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-768x512.jpg 768w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-800x533.jpg 800w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-1076x717.jpg 1076w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-525x350.jpg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-255x170.jpg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Pruefung-1-251x167.jpg 251w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\r\n\r\n\r\n\r\n<p><strong>Was sind die drei gr\u00f6\u00dften Anforderungen an Rasterwalzen im hochqualitativen Flexodruck?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>Eine immer wieder an uns gestellte Anforderung ist der m\u00f6glichst geringe Rakelverschlei\u00df und die Vermeidung von Score-Lines. Auch in dieser Hinsicht erzielt unsere Keramikoberfl\u00e4che ausgezeichnete Ergebnisse.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Als weiteren wichtigen Punkt sehen wir die konstante und gleichbleibende Farbabgabe als Grundvoraussetzung f\u00fcr einen kontinuierlichen hochqualitativen Druckprozess. Das m\u00fcssen wir gew\u00e4hrleisten.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>W\u00e4hrend der Herstellung sind enge Fertigungstoleranzen und hohe Wiederholgenauigkeit entscheidende Faktoren. Mit unserer permanenten Prozess\u00fcberwachung und Qualit\u00e4tskontrolle durch ein zertifiziertes ISO-System erreichen wir gleichbleibend hohe Standards unserer Rasterwalzen und Sleeves.<\/em><\/p>\r\n\r\n\r\n\r\n<p><strong>Welchen Einfluss hat die Keramikbeschichtung sowie N\u00e4pfchenform und Linienaufl\u00f6sung der Rasterwalze auf das Druckergebnis?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>Wir sagen immer: Ohne gute Grundschicht, keine gute Rasterwalze. Ich m\u00f6chte in diesem Zusammenhang die selbstbewusste Behauptung aufstellen, dass sich kaum ein anderes Unternehmen unserer Branche derart intensiv mit der Beschichtung von Leichtbaukomponenten aus CFK-Materialien und Aluminium auseinandersetzt.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>F\u00fcr unsere Rasterwalzen bedeutet dies minimale Porosit\u00e4t gepaart\u00a0mit geringer Oberfl\u00e4chenspannung und einer hohen Ausgewogenheit von H\u00e4rte und Duktilit\u00e4t. Im Gravurprozess erm\u00f6glicht die geringe Porosit\u00e4t der Keramik ein gleichm\u00e4\u00dfiges Umschmelzen, was zu einer becherartigen Zellstruktur f\u00fchrt.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Im Verh\u00e4ltnis zum Volumen ist diese Struktur sehr flach ausgef\u00fchrt und erm\u00f6glicht somit eine ideale Zellentleerung. F\u00fcr besonders anspruchsvolle Druckjobs haben wir daraus unser INOcell-Programm entwickelt, mit dem ein ideales von Tiefen und Volumen erreicht wird.<\/em><\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">\u00a0<\/h4>\r\n\r\n\r\n\r\n<p><strong>Beschreiben Sie bitte die Methodik von Inometa, um f\u00fcr schwierige Anwendungen f\u00fcr den Druck flexibler Verpackungen (z. B. Wei\u00dfauftrag, Motive mit hoher Rasteraufl\u00f6sung und Rasterverl\u00e4ufen) die optimal geeignete Rasterwalzen-Spezifikation zu definieren?<br \/><\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>Stephan Palenga:<\/strong>\u00a0<em>Grunds\u00e4tzlich haben wir f\u00fcr die unterschiedlichen Druckanwendungen unserer Kunden entsprechende Standardempfehlungen. Dennoch favorisieren wir aber den engen Austausch mit unseren Kunden, um auf dieser Basis ma\u00dfgeschneiderte und optimale L\u00f6sung zu finden.<\/em><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" class=\"wp-image-1115\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1.jpg\" alt=\"Inometa AniCAM\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1.jpg 1200w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-300x200.jpg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-1024x683.jpg 1024w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-768x512.jpg 768w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-800x533.jpg 800w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-1076x717.jpg 1076w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-525x350.jpg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-255x170.jpg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-AniCAM-1-251x167.jpg 251w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\r\n\r\n\r\n\r\n<p><strong>Inometa fertigt und vertreibt seine Rasterwalzen\/Rastersleeves unter dem Markennamen INOflex. Was unterscheidet die INOflex-Produkte von denen anderer Hersteller?<\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong><br \/>Stephan Palenga:<\/strong>\u00a0<em>Wie bereits erw\u00e4hnt, steht bei all unseren Aktivit\u00e4ten der Systemgedanke im Vordergrund. Schwingungen oder auch Rakelspr\u00fcnge (\u201eBouncing\u201c) sind im Flexodruck ein immer wiederkehrendes Problem. Hier verlassen wir uns bei der Auslegung und Berechnung nicht allein auf den schwingunsd\u00e4mpfenden Werkstoff CFK, sondern betrachten das gesamte Druckwerk. Der gro\u00dfe Vorteil einer derartigen Vorgehensweise besteht darin, dass wir s\u00e4mtliche Komponenten liefern und daher deren Berechnung und Konstruktion aufeinander abstimmen k\u00f6nnen. Das umfasst das gesamte Spektrum von Tr\u00e4gerstangen f\u00fcr Druck- und Rasterwalzensleeves, hydraulischen und pneumatischen Adaptersystemen bis hin zu Sleeves f\u00fcr die Plattenmontage und selbstverst\u00e4ndlich Rasterwalzen sowie Rasterwalzensleeves. So erreichen wir mit hochsteifen Einzelkomponenten eine minimalste Gesamtverformung des kompletten Systems. Au\u00dferdem fertigen wir bei all unseren Produkten durchg\u00e4ngig nach engsten Form- und Lagetoleranzen.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Wir erm\u00f6glichen unseren Kunden mit unseren Entwicklungen, L\u00f6sungen, Produkten und Dienstleistungen Wettbewerbsvorteile. Abschlie\u00dfend m\u00f6chte ich noch darauf hinweisen, dass alle unsere INOflex-Produkte f\u00fcr Anwendungen im High-End-Bereich des Flexodrucks angesiedelt sind.<\/em><\/p>\r\n\r\n\r\n\r\n<p>Erschienen in Flexo+Tief-Druck 02\/2019. Text: Ansgar Wessendorf<\/p>\r\n\r\n\r\n\r\n<p><a href=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/INOMETA_Flexo-Tiefdruck-Interview-Stephan-Palenga_low.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Download: Flexo+Tief-Druck Ausgabe 02\/2019 \u2013 Interview Stephan Palenga<\/a><\/p>\r\n\r\n\r\n<div class=\"wp-bootstrap-blocks-row row p-0 pt-4\">\n\t\r\n\r\n\n<div class=\"col-12 col-md-4 linkboxen\">\n\t\t\t\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Produkte<\/h4>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.inometa.de\/en\/produkte\/\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"337\" class=\"wp-image-3198\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner.jpg\" alt=\"\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner.jpg 700w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner-300x144.jpg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner-525x253.jpg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner-255x123.jpg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2023\/02\/produkte-banner-251x121.jpg 251w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\r\n\t<\/div>\n\r\n\r\n\n<div class=\"col-12 col-md-4 linkboxen\">\n\t\t\t\r\n\r\n\r\n<h4 class=\"wp-block-heading\">\u00dcber INOMETA<\/h4>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.inometa.de\/unternehmen\/uber-inometa\/\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"337\" class=\"wp-image-65\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA.jpeg\" alt=\"\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA.jpeg 700w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA-300x144.jpeg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA-525x253.jpeg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA-255x123.jpeg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberINOMETA-251x121.jpeg 251w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\r\n\t<\/div>\n\r\n\r\n\n<div class=\"col-12 col-md-4 linkboxen\">\n\t\t\t\r\n\r\n\r\n<h4 class=\"wp-block-heading\">\u00dcber AVANCO<\/h4>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.inometa.de\/en\/die-avanco-gruppe\/ueber-avanco\/\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"337\" class=\"wp-image-359\" src=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco.jpg\" alt=\"\" srcset=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco.jpg 700w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco-300x144.jpg 300w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco-525x253.jpg 525w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco-255x123.jpg 255w, https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/ueberAvanco-251x121.jpg 251w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\r\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Rasterwalze nimmt in der Flexodruckmaschine im Farbu\u0308bertragungsprozess eine herausragende Stellung ein.<\/p>\n <a href=\"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/\">read more<\/a>","protected":false},"author":3,"featured_media":1108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rasterwalzen im Flexodruck | INOMETA<\/title>\n<meta name=\"description\" content=\"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rasterwalzen im Flexodruck | INOMETA\" \/>\n<meta property=\"og:description\" content=\"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/\" \/>\n<meta property=\"og:site_name\" content=\"INOMETA\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-09T09:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T06:35:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"avanco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"avanco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/\"},\"author\":{\"name\":\"avanco\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#\\\/schema\\\/person\\\/1ad6ff166620f902e42b4b6aed146ad1\"},\"headline\":\"INOMETA \u2013 Bei uns steht der Systemgedanke im Vordergrund\",\"datePublished\":\"2019-05-09T09:36:00+00:00\",\"dateModified\":\"2023-06-14T06:35:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/\"},\"wordCount\":1229,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Inometa-Stephan-Palenga-Beitragsbild.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/\",\"name\":\"Rasterwalzen im Flexodruck | INOMETA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Inometa-Stephan-Palenga-Beitragsbild.jpg\",\"datePublished\":\"2019-05-09T09:36:00+00:00\",\"dateModified\":\"2023-06-14T06:35:18+00:00\",\"description\":\"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Inometa-Stephan-Palenga-Beitragsbild.jpg\",\"contentUrl\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Inometa-Stephan-Palenga-Beitragsbild.jpg\",\"width\":400,\"height\":225,\"caption\":\"Inometa-\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/news\\\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INOMETA \u2013 Bei uns steht der Systemgedanke im Vordergrund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/\",\"name\":\"INOMETA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#organization\",\"name\":\"INOMETA\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/inometa-BaseLogo.png\",\"contentUrl\":\"https:\\\/\\\/www.inometa.de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/inometa-BaseLogo.png\",\"width\":170,\"height\":75,\"caption\":\"INOMETA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/#\\\/schema\\\/person\\\/1ad6ff166620f902e42b4b6aed146ad1\",\"name\":\"avanco\",\"url\":\"https:\\\/\\\/www.inometa.de\\\/en\\\/author\\\/avanco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rasterwalzen im Flexodruck | INOMETA","description":"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/","og_locale":"en_US","og_type":"article","og_title":"Rasterwalzen im Flexodruck | INOMETA","og_description":"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.","og_url":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/","og_site_name":"INOMETA","article_published_time":"2019-05-09T09:36:00+00:00","article_modified_time":"2023-06-14T06:35:18+00:00","og_image":[{"width":400,"height":225,"url":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg","type":"image\/jpeg"}],"author":"avanco","twitter_card":"summary_large_image","twitter_misc":{"Written by":"avanco","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#article","isPartOf":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/"},"author":{"name":"avanco","@id":"https:\/\/www.inometa.de\/en\/#\/schema\/person\/1ad6ff166620f902e42b4b6aed146ad1"},"headline":"INOMETA \u2013 Bei uns steht der Systemgedanke im Vordergrund","datePublished":"2019-05-09T09:36:00+00:00","dateModified":"2023-06-14T06:35:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/"},"wordCount":1229,"publisher":{"@id":"https:\/\/www.inometa.de\/en\/#organization"},"image":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/","url":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/","name":"Rasterwalzen im Flexodruck | INOMETA","isPartOf":{"@id":"https:\/\/www.inometa.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#primaryimage"},"image":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg","datePublished":"2019-05-09T09:36:00+00:00","dateModified":"2023-06-14T06:35:18+00:00","description":"Die Rasterwalze in der Flexodruckmaschine im Farbu\u0308bertragungsprozess ist essentiell. Allerdings sind weitere Faktoren zu beachten.","breadcrumb":{"@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#primaryimage","url":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg","contentUrl":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/11\/Inometa-Stephan-Palenga-Beitragsbild.jpg","width":400,"height":225,"caption":"Inometa-"},{"@type":"BreadcrumbList","@id":"https:\/\/www.inometa.de\/en\/news\/inometa-bei-uns-steht-der-systemgedanke-im-vordergrund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inometa.de\/en\/"},{"@type":"ListItem","position":2,"name":"INOMETA \u2013 Bei uns steht der Systemgedanke im Vordergrund"}]},{"@type":"WebSite","@id":"https:\/\/www.inometa.de\/en\/#website","url":"https:\/\/www.inometa.de\/en\/","name":"INOMETA","description":"","publisher":{"@id":"https:\/\/www.inometa.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inometa.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.inometa.de\/en\/#organization","name":"INOMETA","url":"https:\/\/www.inometa.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inometa.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/inometa-BaseLogo.png","contentUrl":"https:\/\/www.inometa.de\/wp-content\/uploads\/sites\/2\/2022\/09\/inometa-BaseLogo.png","width":170,"height":75,"caption":"INOMETA"},"image":{"@id":"https:\/\/www.inometa.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.inometa.de\/en\/#\/schema\/person\/1ad6ff166620f902e42b4b6aed146ad1","name":"avanco","url":"https:\/\/www.inometa.de\/en\/author\/avanco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/posts\/4674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/comments?post=4674"}],"version-history":[{"count":1,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/posts\/4674\/revisions"}],"predecessor-version":[{"id":4794,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/posts\/4674\/revisions\/4794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/media\/1108"}],"wp:attachment":[{"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/media?parent=4674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/categories?post=4674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inometa.de\/en\/wp-json\/wp\/v2\/tags?post=4674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}